{"id":25,"count":1,"description":"","link":"https:\/\/esportstop.lt\/en\/tag\/party\/","name":"PARTY","slug":"party","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PARTY Archives - Esports Top<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esportstop.lt\/en\/tag\/party\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PARTY Archives - Esports Top\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esportstop.lt\/en\/tag\/party\/\" \/>\n<meta property=\"og:site_name\" content=\"Esports Top\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EsportoTopas\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/esportstop.lt\\\/tag\\\/party\\\/\",\"url\":\"https:\\\/\\\/esportstop.lt\\\/tag\\\/party\\\/\",\"name\":\"PARTY Archives - Esports Top\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportstop.lt\\\/#website\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esportstop.lt\\\/#website\",\"url\":\"https:\\\/\\\/esportstop.lt\\\/\",\"name\":\"Esports Top\",\"description\":\"Tavo \u017eaidim\u0173 ir esporto naujienos!\",\"publisher\":{\"@id\":\"https:\\\/\\\/esportstop.lt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esportstop.lt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esportstop.lt\\\/#organization\",\"name\":\"Esports Top\",\"url\":\"https:\\\/\\\/esportstop.lt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/esportstop.lt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/esportstop.lt\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/star-neon2-e1649787740747.png\",\"contentUrl\":\"https:\\\/\\\/esportstop.lt\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/star-neon2-e1649787740747.png\",\"width\":570,\"height\":576,\"caption\":\"Esports Top\"},\"image\":{\"@id\":\"https:\\\/\\\/esportstop.lt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EsportsTopEu\",\"https:\\\/\\\/x.com\\\/EsportoTopas\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PARTY Archives - Esports Top","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esportstop.lt\/en\/tag\/party\/","og_locale":"en_GB","og_type":"article","og_title":"PARTY Archives - Esports Top","og_url":"https:\/\/esportstop.lt\/en\/tag\/party\/","og_site_name":"Esports Top","twitter_card":"summary_large_image","twitter_site":"@EsportoTopas","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/esportstop.lt\/tag\/party\/","url":"https:\/\/esportstop.lt\/tag\/party\/","name":"PARTY Archives - Esports Top","isPartOf":{"@id":"https:\/\/esportstop.lt\/#website"},"inLanguage":"en-GB"},{"@type":"WebSite","@id":"https:\/\/esportstop.lt\/#website","url":"https:\/\/esportstop.lt\/","name":"Esports Top","description":"Tavo \u017eaidim\u0173 ir esporto naujienos!","publisher":{"@id":"https:\/\/esportstop.lt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esportstop.lt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/esportstop.lt\/#organization","name":"Esports Top","url":"https:\/\/esportstop.lt\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/esportstop.lt\/#\/schema\/logo\/image\/","url":"https:\/\/esportstop.lt\/wp-content\/uploads\/2022\/04\/star-neon2-e1649787740747.png","contentUrl":"https:\/\/esportstop.lt\/wp-content\/uploads\/2022\/04\/star-neon2-e1649787740747.png","width":570,"height":576,"caption":"Esports Top"},"image":{"@id":"https:\/\/esportstop.lt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EsportsTopEu","https:\/\/x.com\/EsportoTopas"]}]}},"_links":{"self":[{"href":"https:\/\/esportstop.lt\/en\/wp-json\/wp\/v2\/tags\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportstop.lt\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/esportstop.lt\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/esportstop.lt\/en\/wp-json\/wp\/v2\/posts?tags=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}